{"id":17,"date":"2019-10-25T21:05:30","date_gmt":"2019-10-25T19:05:30","guid":{"rendered":"http:\/\/herste.de\/spielmannszug\/?page_id=17"},"modified":"2024-01-21T12:48:16","modified_gmt":"2024-01-21T11:48:16","slug":"news","status":"publish","type":"page","link":"https:\/\/herste.de\/spielmannszug\/news\/","title":{"rendered":"aktuelle News"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\">Wir suchen &#8211; neue aktive Spielleute<\/h4>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"732\" height=\"1024\" src=\"https:\/\/herste.de\/spielmannszug\/wp-content\/uploads\/2024\/01\/AZUB_2022_FLYER_02-732x1024.jpg\" alt=\"\" class=\"wp-image-850\" srcset=\"https:\/\/herste.de\/spielmannszug\/wp-content\/uploads\/2024\/01\/AZUB_2022_FLYER_02-732x1024.jpg 732w, https:\/\/herste.de\/spielmannszug\/wp-content\/uploads\/2024\/01\/AZUB_2022_FLYER_02-214x300.jpg 214w, https:\/\/herste.de\/spielmannszug\/wp-content\/uploads\/2024\/01\/AZUB_2022_FLYER_02-768x1075.jpg 768w, https:\/\/herste.de\/spielmannszug\/wp-content\/uploads\/2024\/01\/AZUB_2022_FLYER_02-1098x1536.jpg 1098w, https:\/\/herste.de\/spielmannszug\/wp-content\/uploads\/2024\/01\/AZUB_2022_FLYER_02.jpg 1170w\" sizes=\"auto, (max-width: 732px) 100vw, 732px\" \/><\/figure>\n<\/div>\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>R\u00fcckblick &#8222;Sommerfest 2019&#8220;<\/strong><\/h4>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"479\" src=\"https:\/\/herste.de\/spielmannszug\/wp-content\/uploads\/2019\/10\/SOF_2019_01-1024x479.jpg\" alt=\"\" class=\"wp-image-19\" style=\"width:768px;height:359px\" srcset=\"https:\/\/herste.de\/spielmannszug\/wp-content\/uploads\/2019\/10\/SOF_2019_01-1024x479.jpg 1024w, https:\/\/herste.de\/spielmannszug\/wp-content\/uploads\/2019\/10\/SOF_2019_01-300x140.jpg 300w, https:\/\/herste.de\/spielmannszug\/wp-content\/uploads\/2019\/10\/SOF_2019_01-768x360.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Teilnehmer am Bogenschie\u00dfen<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Unser diesj\u00e4hriges Sommerfest fand unter dem Motto \u201eBogenschie\u00dfen\u201c am 7. September 2019 auf dem Sportplatz des SV 13 Herste statt.<br><br>Nach einer kurzen Anleitung und Hinweisen auf die entsprechenden Sicherheitsvorschriften durch den Ausrichter \u201eBogenzeit\u201c aus Paderborn, konnten die Teilnehmer ihre Treffsicherheit auf die 4 Zielscheiben in mehreren Durchg\u00e4ngen verfeinern und optimieren.<br>Hier stand nat\u00fcrlich des Spa\u00df im Vordergrund, aber ein gewisser Ehrgeiz, den optimalen Treffer zu landen, konnte man den Teilnehmern nicht absprechen.<br>Nach einer Finalrunde standen am Ende die Sieger fest und wurden im Rahmen einer Siegerehrung mit entsprechenden Preisen ausgezeichnet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zudem konnte sich jeder Teilnehmer bei Kaffee und Kuchen und sp\u00e4ter bei Spezialit\u00e4ten vom Grill und k\u00fchlen Getr\u00e4nken ausgiebig st\u00e4rken.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Am sp\u00e4teren Abend, in einer sommerlichen Nacht bei lauschigen Temperaturen, kam der Partyspa\u00df nicht zu kurz und es wurde bis in den fr\u00fchen Morgen getanzt, gefeiert und gesungen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wir suchen &#8211; neue aktive Spielleute R\u00fcckblick &#8222;Sommerfest 2019&#8220; Unser diesj\u00e4hriges Sommerfest fand unter dem Motto \u201eBogenschie\u00dfen\u201c am 7. September 2019 auf dem Sportplatz des SV 13 Herste statt. Nach einer kurzen Anleitung und Hinweisen auf die entsprechenden Sicherheitsvorschriften durch den Ausrichter \u201eBogenzeit\u201c aus Paderborn, konnten die Teilnehmer ihre Treffsicherheit auf die 4 Zielscheiben in&hellip;<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-17","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/herste.de\/spielmannszug\/wp-json\/wp\/v2\/pages\/17","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/herste.de\/spielmannszug\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/herste.de\/spielmannszug\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/herste.de\/spielmannszug\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/herste.de\/spielmannszug\/wp-json\/wp\/v2\/comments?post=17"}],"version-history":[{"count":35,"href":"https:\/\/herste.de\/spielmannszug\/wp-json\/wp\/v2\/pages\/17\/revisions"}],"predecessor-version":[{"id":852,"href":"https:\/\/herste.de\/spielmannszug\/wp-json\/wp\/v2\/pages\/17\/revisions\/852"}],"wp:attachment":[{"href":"https:\/\/herste.de\/spielmannszug\/wp-json\/wp\/v2\/media?parent=17"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}